{"id":2730,"date":"2022-09-01T14:12:37","date_gmt":"2022-09-01T12:12:37","guid":{"rendered":"https:\/\/moivalencia.es\/current-events\/"},"modified":"2024-10-09T13:58:37","modified_gmt":"2024-10-09T11:58:37","slug":"current-events","status":"publish","type":"page","link":"https:\/\/moivalencia.es\/ca\/current-events\/","title":{"rendered":"Esdeveniments actuals"},"content":{"rendered":"\n\n<header id=\"navigation\" class=\"navigation   show\">\n\n  \n<div class=\"nav-bar c header--transparent desktop\">\n\n  <div class=\"nav-bar__left\">\n    <a href=\"https:\/\/moivalencia.es\/ca\/\" aria-label=\"Museum of Illusions Valencia\" data-home=\"true\" class=\"logo js-close-menu\">\n      <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moivalencia.es\/wp-content\/uploads\/2024\/10\/moi-athens-EN@2x.png\" rel=\"preload\" width=\"1\" height=\"1\" alt=\"Museum of Illusions\">\n    <\/a>\n\n    <div class=\"show desktop\">\n          <nav class=\"mega-menu\" >\n      <ul>\n        \n<li >\n      <a href=\"https:\/\/moivalencia.es\/exposiciones\/\" \n                        aria-label=\"Exposiciones\">\n              <span>Exposiciones<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n  <span class=\"trigger\">    <a href=\"#\" \n                        aria-label=\"Grupos y Eventos\">\n              <span>Grupos y Eventos<\/span>\n    <\/a>\n  <svg class=\"icon\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 17 10\">\n  <path opacity=\".9\" d=\"m16 1.167-7.5 7.5-7.5-7.5\" stroke=\"#fff\" stroke-width=\"1.667\"\/>\n<\/svg><\/span>\n    <ul>\n    \n<li >\n      <a href=\"https:\/\/moivalencia.es\/eventos\/evento-corporativo\/\" \n                        aria-label=\"Evento corporativo\">\n              <span>Evento corporativo<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/eventos\/team-building\/\" \n                        aria-label=\"Team building\">\n              <span>Team building<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/eventos\/fiestas-de-cumpleanos\/\" \n                        aria-label=\"Fiestas de cumplea\u00f1os\">\n              <span>Fiestas de cumplea\u00f1os<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/grupos\/excursiones-escolares\/?_gl=1*cnfpk6*_up*MQ..*_gs*MQ..&gclid=CjwKCAjw687NBhB4EiwAQ645dm7uJf9yfdzU_jTA_OZcZjBeJFwM6fVzCnvDnbq7FW9b2kZEEG6riBoCwPwQAvD_BwE&gbraid=0AAAAA_r1whLLLdhu6e3waca7W9xKLeUgB\" \n                        aria-label=\"Excursiones escolares\">\n              <span>Excursiones escolares<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/grupos\/grupos\/?_gl=1*cnfpk6*_up*MQ..*_gs*MQ..&gclid=CjwKCAjw687NBhB4EiwAQ645dm7uJf9yfdzU_jTA_OZcZjBeJFwM6fVzCnvDnbq7FW9b2kZEEG6riBoCwPwQAvD_BwE&gbraid=0AAAAA_r1whLLLdhu6e3waca7W9xKLeUgB\" \n                        aria-label=\"Visitas en grupo\">\n              <span>Visitas en grupo<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/informacion-para-guias-oficiales\/\" \n                        aria-label=\"Informaci\u00f3n para gu\u00edas oficiales\">\n              <span>Informaci\u00f3n para gu\u00edas oficiales<\/span>\n    <\/a>\n  \n  \n<\/li>  <\/ul>\n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/eventos-actuales\/\" \n                        aria-label=\"Eventos actuales\">\n              <span>Eventos actuales<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/juegos-e-ilusiones\/\" \n                        aria-label=\"TIENDA\">\n              <span>TIENDA<\/span>\n    <\/a>\n  \n  \n<\/li>      <\/ul>\n    <\/nav>\n      <\/div>\n    <div class=\"show\">\n\n              <div class=\"submenu desktop\">\n          <button class=\"submenu__trigger js-submenu-trigger\" aria-label=\"Submenu trigger\" aria-expanded=\"false\" aria-controls=\"submenu-nav\" aria-haspopup=\"true\">\n            <svg class=\"icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 17 3\">\n  <circle class=\"c1\" cx=\"1.5\" cy=\"1.5\" r=\"1.5\" fill=\"#fff\"\/>\n  <circle class=\"c2\" cx=\"8.5\" cy=\"1.5\" r=\"1.5\" fill=\"#fff\"\/>\n  <circle class=\"c3\" cx=\"15.5\" cy=\"1.5\" r=\"1.5\" fill=\"#fff\"\/>\n<\/svg>\n          <\/button>\n\n              <nav class=\"\" >\n      <ul>\n        \n<li >\n      <a href=\"https:\/\/moivalencia.es\/about-us\/\" \n                        aria-label=\"Con\u00f3cenos\">\n              <span>Con\u00f3cenos<\/span>\n    <\/a>\n  \n  \n<\/li>      <\/ul>\n    <\/nav>\n  \n        <\/div>\n          <\/div>\n  <\/div>\n\n  <div class=\"nav-bar__right show\">\n    <div class=\"cta-menu  \">\n          <nav class=\"cta-menu\" >\n      <ul>\n        \n<li >\n      <a href=\"https:\/\/moivalencia.es\/contacto\/\" aria-label=\"Contacto\">\n              <span>Contacto<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/shop.articketing.com\/monuments\/moi-valencia\/tickets\" aria-label=\"Comprar entradas\" target=\"_blank\" rel=\"noopener\">\n              <span>Comprar entradas<\/span>\n    <\/a>\n  \n  \n<\/li>      <\/ul>\n    <\/nav>\n                  <\/div>\n\n          <button class=\"lang js-lang-trigger\" aria-expanded=\"false\" aria-controls=\"submenu-nav\" aria-haspopup=\"true\">\n        \n<div class=\"wpml-ls-statics-shortcode_actions wpml-ls wpml-ls-legacy-list-horizontal\">\n\t<ul><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-ca wpml-ls-current-language wpml-ls-first-item wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/moivalencia.es\/ca\/\" class=\"wpml-ls-link\">\n                    <span class=\"wpml-ls-native\">VAL<\/span><\/a>\n\t\t\t<\/li><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-en wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/moivalencia.es\/en\/\" class=\"wpml-ls-link\">\n                    <span class=\"wpml-ls-native\" lang=\"en\">EN<\/span><\/a>\n\t\t\t<\/li><li class=\"wpml-ls-slot-shortcode_actions wpml-ls-item wpml-ls-item-es wpml-ls-last-item wpml-ls-item-legacy-list-horizontal\">\n\t\t\t\t<a href=\"https:\/\/moivalencia.es\/\" class=\"wpml-ls-link\">\n                    <span class=\"wpml-ls-native\" lang=\"es\">ES<\/span><\/a>\n\t\t\t<\/li><\/ul>\n<\/div>\n        <svg class=\"icon\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 17 10\">\n  <path opacity=\".9\" d=\"m16 1.167-7.5 7.5-7.5-7.5\" stroke=\"#fff\" stroke-width=\"1.667\"\/>\n<\/svg>      <\/button>\n        <button type=\"button\" aria-label=\"Menu\" class=\"hamburger js-menu-trigger\" data-cursor=\"hamburger\">\n  <div class=\"hamburger__inner\">\n    <span class=\"line line--1\"><\/span>\n    <span class=\"line line--2\"><\/span>\n    <span class=\"line line--3\"><\/span>\n  <\/div>\n<\/button>\n  <\/div>\n<\/div>\n<div class=\"nav-menu\" style=\"opacity:0;visibility:hidden;\">\n  <div class=\"c\">\n    <div class=\"cta-menu  \">\n                      <nav class=\"cta-menu\" >\n      <ul>\n        \n<li >\n      <a href=\"https:\/\/moivalencia.es\/contacto\/\" aria-label=\"Contacto\">\n              <span>Contacto<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/shop.articketing.com\/monuments\/moi-valencia\/tickets\" aria-label=\"Comprar entradas\" target=\"_blank\" rel=\"noopener\">\n              <span>Comprar entradas<\/span>\n    <\/a>\n  \n  \n<\/li>      <\/ul>\n    <\/nav>\n      <\/div>\n\n        <nav class=\"main-menu\" >\n      <ul>\n        \n<li >\n      <a href=\"https:\/\/moivalencia.es\/exposiciones\/\" class=\"js-close-menu\" aria-label=\"Exposiciones\">\n              <span>Exposiciones<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n  <span class=\"trigger\">    <a href=\"#\" \n      class=\"js-close-menu\"                  aria-label=\"Grupos y Eventos\">\n              <span>Grupos y Eventos<\/span>\n    <\/a>\n  <svg class=\"icon\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 17 10\">\n  <path opacity=\".9\" d=\"m16 1.167-7.5 7.5-7.5-7.5\" stroke=\"#fff\" stroke-width=\"1.667\"\/>\n<\/svg><\/span>\n    <ul>\n    \n<li >\n      <a href=\"https:\/\/moivalencia.es\/eventos\/evento-corporativo\/\" class=\"js-close-menu\" aria-label=\"Evento corporativo\">\n              <span>Evento corporativo<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/eventos\/team-building\/\" class=\"js-close-menu\" aria-label=\"Team building\">\n              <span>Team building<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/eventos\/fiestas-de-cumpleanos\/\" class=\"js-close-menu\" aria-label=\"Fiestas de cumplea\u00f1os\">\n              <span>Fiestas de cumplea\u00f1os<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/grupos\/excursiones-escolares\/?_gl=1*cnfpk6*_up*MQ..*_gs*MQ..&amp;gclid=CjwKCAjw687NBhB4EiwAQ645dm7uJf9yfdzU_jTA_OZcZjBeJFwM6fVzCnvDnbq7FW9b2kZEEG6riBoCwPwQAvD_BwE&amp;gbraid=0AAAAA_r1whLLLdhu6e3waca7W9xKLeUgB\" class=\"js-close-menu\" aria-label=\"Excursiones escolares\">\n              <span>Excursiones escolares<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/grupos\/grupos\/?_gl=1*cnfpk6*_up*MQ..*_gs*MQ..&amp;gclid=CjwKCAjw687NBhB4EiwAQ645dm7uJf9yfdzU_jTA_OZcZjBeJFwM6fVzCnvDnbq7FW9b2kZEEG6riBoCwPwQAvD_BwE&amp;gbraid=0AAAAA_r1whLLLdhu6e3waca7W9xKLeUgB\" class=\"js-close-menu\" aria-label=\"Visitas en grupo\">\n              <span>Visitas en grupo<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/informacion-para-guias-oficiales\/\" class=\"js-close-menu\" aria-label=\"Informaci\u00f3n para gu\u00edas oficiales\">\n              <span>Informaci\u00f3n para gu\u00edas oficiales<\/span>\n    <\/a>\n  \n  \n<\/li>  <\/ul>\n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/eventos-actuales\/\" class=\"js-close-menu\" aria-label=\"Eventos actuales\">\n              <span>Eventos actuales<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/juegos-e-ilusiones\/\" class=\"js-close-menu\" aria-label=\"TIENDA\">\n              <span>TIENDA<\/span>\n    <\/a>\n  \n  \n<\/li>      <\/ul>\n    <\/nav>\n  \n\n        <nav class=\"sub-menu\" >\n      <ul>\n        \n<li >\n      <a href=\"https:\/\/moivalencia.es\/about-us\/\" class=\"js-close-menu\" aria-label=\"Con\u00f3cenos\">\n              <span>Con\u00f3cenos<\/span>\n    <\/a>\n  \n  \n<\/li>      <\/ul>\n    <\/nav>\n  \n  <\/div>\n<\/div>\n\n<\/header>\n\n\n<section class=\"cover smaller center\">\n  <div class=\"c\">\n    \n          <div class=\"headline h4 lowercase\">\n                <h2 class=\"title h4\">\n          Esdeveniments actuals        <\/h2>\n      <\/div>\n    \n          <\/div>\n<\/section>\n\n\n\n<section class=\"current-events\" data-total=\"3\">\n  <div class=\"c\">\n    <div class=\"current-events__items\">\n              <ul>\n                                  <li>\n              \n<article class=\"current-event-card current-event-card--\">\n    <div class=\"current-event-card__col\">\n                    <div class=\"image-holder\">\n                <a href=\"https:\/\/moivalencia.es\/ca\/current-event\/dia-internacional-de-los-museos\/\" aria-label=\"Dia Internacional dels Museus\" class=\"image image--style-1\">\n                    <img decoding=\"async\" class=\"image__element\"\n                        loading=\"lazy\"\n                        src=\"https:\/\/moivalencia.es\/wp-content\/uploads\/2026\/05\/Image2.jpg\"\n                        alt=\"Dia Internacional dels Museus\"\n                    >\n                <\/a>\n            <\/div>\n        \n        <div class=\"current-event-card__content\">\n            <div class=\"event-dates\">\n                                <div class=\"date\">\n                                                                                            <span><\/span>\n                                                            <\/div>\n                <div class=\"time\">\n                                    <\/div>\n            <\/div>\n            <h2 class=\"title h4\">Dia Internacional dels Museus<\/h2>\n\n                            <p>Celebra amb nosaltres el Dia Internacional dels Museus! Durant tota la setmana hem\npreparat activitats especials, sorpreses per als m\u00e9s menuts i promocions exclusives perqu\u00e8\ngaudisques d\u2019una experi\u00e8ncia encara m\u00e9s divertida i inoblidable.\n<br>\n<br>\nVine a descobrir les nostres il\u00b7lusions interactives, participa en activitats familiars i aprofita\ndescomptes \u00fanics durant estos dies especials.<\/p>\n            \n            <div class=\"cta\">\n                                    <a class=\"btn btn--m\" href=\"https:\/\/shop.articketing.com\/monuments\/museum-of-illusions-valencia\/tickets?_gl=1%2a12yx15w%2a_gcl_aw%2aR0NMLjE3Nzg1MDE0ODQuQ2owS0NRandfSVhRQmhDa0FSSXNBRHFFTGJLY3R3U1BlaDR3NUE1UGpqT2ZWVWh2NXdiNEVpMVVRUUNxZ1hRcGZaTDExelRjbTRsMGpkWWFBcXR1RUFMd193Y0I.%2a_gcl_au%2aNTQ4NDEwOTEuMTc3Njc2MTU0MQ..&amp;s=entrada-museum-of-illusions-acceso-general\" aria-label=\"RESERVAR ENTRADES\" target=\"_blank\" rel=\"noopener\">RESERVAR ENTRADES<\/a>\n                                                    <div class=\"static-script-container\">\n                                            <\/div>\n                                <a href=\"https:\/\/moivalencia.es\/ca\/current-event\/dia-internacional-de-los-museos\/\" class=\"ll ll--s\">M\u00e9s informaci\u00f3<\/a>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/article>\n            <\/li>\n                  <\/ul>\n          <\/div>\n  <\/div>\n<\/section>\n\n\n              <ul class=\"mobile-menu\">\n                  <li>\n            <a href=\"https:\/\/shop.articketing.com\/monuments\/museum-of-illusions-valencia\/tickets\" target=\"_blank\" rel=\"noopener\">\n              <span><svg class=\"icon ticket\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 25 25\">\n  <path fill=\"#fff\" d=\"m23.05 9.026-2-2.002a.907.907 0 0 0-1.225-.045 1.398 1.398 0 0 1-1.891-.073 1.398 1.398 0 0 1-.073-1.89.908.908 0 0 0-.045-1.225l-2.004-2.004a.903.903 0 0 0-1.276 0l-3.191 3.191a1.809 1.809 0 0 0-.435.703.35.35 0 0 1-.219.22 1.805 1.805 0 0 0-.703.434l-8.184 8.184a.903.903 0 0 0 0 1.276l2.004 2.002a.907.907 0 0 0 1.225.045 1.392 1.392 0 0 1 1.964 1.964.907.907 0 0 0 .045 1.225l2.002 2.002a.903.903 0 0 0 1.276 0l8.184-8.184c.197-.198.346-.438.435-.703a.35.35 0 0 1 .22-.22c.264-.088.505-.237.702-.434l3.191-3.191a.904.904 0 0 0 0-1.275ZM12.69 7.681a.725.725 0 0 1-1.026 0l-.522-.522a.726.726 0 0 1 1.026-1.026l.522.522a.726.726 0 0 1 0 1.026Zm1.997 1.996a.726.726 0 0 1-1.027 0l-.499-.499a.725.725 0 0 1 .792-1.184.72.72 0 0 1 .235.158l.499.499a.728.728 0 0 1 0 1.028v-.002Zm1.996 1.997a.724.724 0 0 1-1.027 0l-.499-.5a.726.726 0 0 1 1.027-1.026l.499.5a.724.724 0 0 1 .002 1.028l-.002-.002Zm2.015 2.02a.726.726 0 0 1-1.026 0l-.52-.522a.725.725 0 1 1 1.03-1.024l.519.522a.726.726 0 0 1 0 1.026l-.003-.002Z\"><\/path>\n<\/svg>\n<\/span>\n              <span>Comprar entradas <\/span>\n            <\/a>\n          <\/li>\n                          <li>\n            <a href=\"https:\/\/moivalencia.es\/ca\/contacta-amb-nosaltres\/\">\n              <span><svg class=\"icon pin\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 28 28\">\n  <g clip-path=\"url(#pin)\">\n    <path fill=\"#fff\" d=\"M13.5 4a7.135 7.135 0 0 0-7.125 7.125c0 5.115 6.638 11.522 6.92 11.792a.294.294 0 0 0 .41 0c.282-.27 6.92-6.677 6.92-11.792A7.135 7.135 0 0 0 13.5 4Zm0 10.39a3.266 3.266 0 1 1 0-6.53 3.266 3.266 0 0 1 0 6.53Z\"><\/path>\n  <\/g>\n  <defs>\n    <clipPath id=\"pin\">\n      <path fill=\"#fff\" d=\"M0 0h19v19H0z\" transform=\"translate(4 4)\"><\/path>\n    <\/clipPath>\n  <\/defs>\n<\/svg><\/span>\n              <span>Contacto <\/span>\n            <\/a>\n          <\/li>\n              <\/ul>\n      \n\n<footer id=\"footer\" class=\"footer\">\n    <div id=\"footer-menu\" class=\"footer-menu\">\n  <div class=\"c\">\n    <div class=\"footer-menu__left\">\n      <div class=\"logo\">\n        <a href=\"\/\" aria-label=\"Museum of Illusions Valencia\">\n          <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/moivalencia.es\/wp-content\/uploads\/2024\/10\/moi-athens-EN@2x.png\" width=\"1\" height=\"1\" alt=\"moi athens en@2x\">\n        <\/a>\n      <\/div>\n      <p class=\"small\">Entra al fascinant m\u00f3n de les il\u00b7lusions on res \u00e9s el que sembla. Visita'ns en el Museu de les Il\u00b7lusions de Val\u00e8ncia i experimenta l'incre\u00efble!<\/p>\n      <ul class=\"contact-info\">\n        <li><a href=\"https:\/\/www.google.com\/maps\/place\/\/data=!4m2!3m1!1s0xd604fb773bcba5d:0xcaa5a249bceebb6b?sa=X&amp;ved=1t:8290&amp;ictx=111\" target=\"_blank\" rel=\"nofollow noopener\" aria-label=\"Get directions to our location\" class=\"ll ll--g tiny\">C\/ de Guillem de Castro, 13, Extramurs, 46007 Val\u00e8ncia, Spain<\/a><\/li>\n        <li><a href=\"mailto:info@moivalencia.es\" target=\"_blank\" rel=\"noreferrer\" class=\"ll ll--g tiny\">info@moivalencia.es<\/a><\/li>\n                          <li><a href=\"tel: +34 603837809\" target=\"_blank\" rel=\"noreferrer\"\n          aria-label=\"Call us at +34 603837809\"\n          class=\"ll ll--g tiny phone\">+34 603837809<\/a><\/li>\n                      <\/ul>\n      <p class=\"h6\">Compartix la teua experi\u00e8ncia<\/p>\n      <ul class=\"social\">\n                  <li><a href=\"https:\/\/www.instagram.com\/moi_valencia\/\" target=\"_blank\" aria-label=\"MOI Instagram\" rel=\"nofollow noopener\"><svg class=\"icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 17 16\">\n  <g fill=\"#fff\" clip-path=\"url(#i)\">\n    <path d=\"M12.135 1h-6.43A3.79 3.79 0 0 0 1.92 4.785v6.435A3.79 3.79 0 0 0 5.705 15h6.435a3.79 3.79 0 0 0 3.785-3.785v-6.43A3.797 3.797 0 0 0 12.135 1Zm2.656 10.215a2.655 2.655 0 0 1-2.651 2.651H5.705a2.655 2.655 0 0 1-2.651-2.65V4.784a2.655 2.655 0 0 1 2.65-2.651h6.436c1.46 0 2.65 1.19 2.65 2.65v6.431Z\"><\/path>\n    <path d=\"M12.051 7.51a3.104 3.104 0 0 0-.887-1.76 3.133 3.133 0 0 0-2.678-.886 3.1 3.1 0 0 0-2.063 1.237 3.124 3.124 0 0 0-.583 2.328c.121.831.56 1.564 1.236 2.063a3.111 3.111 0 0 0 2.329.588 3.103 3.103 0 0 0 2.063-1.237 3.114 3.114 0 0 0 .583-2.333Zm-2.81 2.45a1.993 1.993 0 0 1-1.488-.373 1.998 1.998 0 0 1-.789-1.32 1.995 1.995 0 0 1 .374-1.49 1.995 1.995 0 0 1 1.32-.788 2.08 2.08 0 0 1 .294-.024c.098 0 .196.01.294.024a2 2 0 0 1 1.694 1.694A2.02 2.02 0 0 1 9.242 9.96Zm3.618-5.899a.565.565 0 0 0-.402-.163.58.58 0 0 0-.401.163.565.565 0 0 0-.163.402c0 .149.06.294.163.4a.565.565 0 0 0 .401.164c.15 0 .294-.06.402-.163a.565.565 0 0 0 .163-.401.546.546 0 0 0-.163-.402Z\"><\/path>\n  <\/g>\n  <!-- <defs>\n    <clipPath id=\"i\">\n      <path fill=\"#fff\" d=\"M0 0h14v14H0z\" transform=\"translate(1.92 1)\"><\/path>\n    <\/clipPath>\n  <\/defs> -->\n<\/svg><\/a><\/li>\n                          <li><a href=\"https:\/\/www.facebook.com\/profile.php?id=61565874137085\" target=\"_blank\" aria-label=\"MOI Facebook\" rel=\"nofollow noopener\"><svg class=\"icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 17 16\">\n  <path d=\"M5.146 8.456H6.68v6.318c0 .125.101.226.226.226h2.602a.226.226 0 0 0 .226-.226V8.486h1.764a.226.226 0 0 0 .225-.2l.267-2.326a.226.226 0 0 0-.224-.251H9.734V4.25c0-.44.237-.663.704-.663h1.328a.226.226 0 0 0 .226-.226V1.227a.226.226 0 0 0-.226-.225h-1.83L9.85 1c-.317 0-1.422.062-2.294.865-.967.89-.832 1.954-.8 2.139v1.705h-1.61a.226.226 0 0 0-.226.225v2.297c0 .124.101.225.226.225Z\"><\/path>\n<\/svg>\n<\/a><\/li>\n                                          <li><a href=\"https:\/\/www.tiktok.com\/@moi_valencia?fbclid=IwY2xjawGoL5lleHRuA2FlbQIxMAABHazKeRmlxJAdZVOPussTOjLXffMwhHrFp7nLTJobM-GBJA-k7I-SWLmkrQ_aem_mMuJKfm2w0nN7ykLIuZJ7A\" target=\"_blank\" aria-label=\"MOI Tiktok\" rel=\"nofollow noopener\"><svg class=\"icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 13 16\">\n  <path fill=\"#fff\" d=\"M11.2239 3.86306c-.0983-.05081-.1939-.10652-.2866-.16689-.2693-.17808-.5163-.38788-.7355-.6249-.54923-.62812-.75429-1.26531-.82933-1.71101h.00259C9.31231.989592 9.33819.750244 9.34272.750244H6.8425V10.4167c0 .1293 0 .2581-.00518.3849 0 .0155-.00194.0297-.00258.0472 0 .0065 0 .0142-.00194.0213v.0059c-.02626.3467-.13733.6817-.32346.9754-.18612.2937-.44158.5372-.74391.7091-.3154.1794-.67214.2735-1.03501.2729-1.1644 0-2.10886-.9496-2.10886-2.1224 0-1.17345.94446-2.12308 2.10886-2.12308.22058 0 .43988.03493.64947.1035l.00323-2.54614c-.63652-.08212-1.28316-.0314-1.8991.14897-.61594.18038-1.18779.48648-1.67947.89898-.43092.37425-.79322.82084-1.0706 1.31965-.105442.18178-.503924.91341-.551794 2.09982-.030404.6727.172072 1.3714.268458 1.6592v.0065c.06016.1695.295627.7491.678586 1.2375.30882.392.6737.7364 1.08289 1.0221v-.0065l.00582.0065c1.20968.8215 2.55197.7678 2.55197.7678.23223-.0097 1.01043 0 1.89408-.4185.98003-.4645 1.53765-1.156 1.53765-1.156.35651-.4133.64001-.8842.83836-1.3927.22641-.5952.30145-1.308.30145-1.5927V5.61677c.03041.01811.43471.28528.43471.28528s.58217.37325 1.48977.61584c.6508.17271 1.5286.20959 1.5286.20959V4.24537c-.3073.03364-.9315-.06339-1.5713-.38166l.0007-.00065Z\"\/>\n<\/svg><\/a><\/li>\n              <\/ul>\n                        <\/div>\n    <div class=\"footer-menu__right\">\n          <nav class=\"footer-1\" >\n      <ul>\n        \n<li >\n      <a href=\"\/contact-us\/\" \n      class=\"h6 ll ll--g\"                  aria-label=\"Donde estamos\">\n              <span>Donde estamos<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"\/contact-us\/#ticket-prices\" \n      class=\"h6 ll ll--g\"                  aria-label=\"Precios\">\n              <span>Precios<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/shop.articketing.com\/monuments\/moi-valencia\/tickets\" class=\"h6 ll ll--g\" aria-label=\"Comprar entradas\" target=\"_blank\" rel=\"noopener\">\n              <span>Comprar entradas<\/span>\n    <\/a>\n  \n  \n<\/li>      <\/ul>\n    <\/nav>\n            <nav class=\"footer-2\" >\n      <ul>\n        \n<li >\n      <a href=\"https:\/\/moivalencia.es\/exposiciones\/\" class=\"ll ll--g\" aria-label=\"Exposiciones\">\n              <span>Exposiciones<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/eventos\/\" class=\"ll ll--g\" aria-label=\"Eventos\">\n              <span>Eventos<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/grupos\/\" class=\"ll ll--g\" aria-label=\"Grupos\">\n              <span>Grupos<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/faq\/\" class=\"ll ll--g\" aria-label=\"Preguntas Frecuentes\">\n              <span>Preguntas Frecuentes<\/span>\n    <\/a>\n  \n  \n<\/li>      <\/ul>\n    <\/nav>\n            <nav class=\"footer-3\" >\n      <ul>\n        \n<li >\n      <a href=\"https:\/\/moivalencia.es\/about-us\/\" class=\"ll ll--g\" aria-label=\"Con\u00f3cenos\">\n              <span>Con\u00f3cenos<\/span>\n    <\/a>\n  \n  \n<\/li>\n<li >\n      <a href=\"https:\/\/moivalencia.es\/declaracion-de-accesibilidad\/\" class=\"ll ll--g\" aria-label=\"Declaraci\u00f3n de Accesibilidad\">\n              <span>Declaraci\u00f3n de Accesibilidad<\/span>\n    <\/a>\n  \n  \n<\/li>      <\/ul>\n    <\/nav>\n        <p class=\"h6\">Compartix la teua experi\u00e8ncia<\/p>\n      <ul class=\"social\">\n                  <li><a href=\"https:\/\/www.instagram.com\/moi_valencia\/\" target=\"_blank\" aria-label=\"MOI Instagram\" rel=\"nofollow noopener\"><svg class=\"icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 17 16\">\n  <g fill=\"#fff\" clip-path=\"url(#i)\">\n    <path d=\"M12.135 1h-6.43A3.79 3.79 0 0 0 1.92 4.785v6.435A3.79 3.79 0 0 0 5.705 15h6.435a3.79 3.79 0 0 0 3.785-3.785v-6.43A3.797 3.797 0 0 0 12.135 1Zm2.656 10.215a2.655 2.655 0 0 1-2.651 2.651H5.705a2.655 2.655 0 0 1-2.651-2.65V4.784a2.655 2.655 0 0 1 2.65-2.651h6.436c1.46 0 2.65 1.19 2.65 2.65v6.431Z\"><\/path>\n    <path d=\"M12.051 7.51a3.104 3.104 0 0 0-.887-1.76 3.133 3.133 0 0 0-2.678-.886 3.1 3.1 0 0 0-2.063 1.237 3.124 3.124 0 0 0-.583 2.328c.121.831.56 1.564 1.236 2.063a3.111 3.111 0 0 0 2.329.588 3.103 3.103 0 0 0 2.063-1.237 3.114 3.114 0 0 0 .583-2.333Zm-2.81 2.45a1.993 1.993 0 0 1-1.488-.373 1.998 1.998 0 0 1-.789-1.32 1.995 1.995 0 0 1 .374-1.49 1.995 1.995 0 0 1 1.32-.788 2.08 2.08 0 0 1 .294-.024c.098 0 .196.01.294.024a2 2 0 0 1 1.694 1.694A2.02 2.02 0 0 1 9.242 9.96Zm3.618-5.899a.565.565 0 0 0-.402-.163.58.58 0 0 0-.401.163.565.565 0 0 0-.163.402c0 .149.06.294.163.4a.565.565 0 0 0 .401.164c.15 0 .294-.06.402-.163a.565.565 0 0 0 .163-.401.546.546 0 0 0-.163-.402Z\"><\/path>\n  <\/g>\n  <!-- <defs>\n    <clipPath id=\"i\">\n      <path fill=\"#fff\" d=\"M0 0h14v14H0z\" transform=\"translate(1.92 1)\"><\/path>\n    <\/clipPath>\n  <\/defs> -->\n<\/svg><\/a><\/li>\n                          <li><a href=\"https:\/\/www.facebook.com\/profile.php?id=61565874137085\" target=\"_blank\" aria-label=\"MOI Facebook\" rel=\"nofollow noopener\"><svg class=\"icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 17 16\">\n  <path d=\"M5.146 8.456H6.68v6.318c0 .125.101.226.226.226h2.602a.226.226 0 0 0 .226-.226V8.486h1.764a.226.226 0 0 0 .225-.2l.267-2.326a.226.226 0 0 0-.224-.251H9.734V4.25c0-.44.237-.663.704-.663h1.328a.226.226 0 0 0 .226-.226V1.227a.226.226 0 0 0-.226-.225h-1.83L9.85 1c-.317 0-1.422.062-2.294.865-.967.89-.832 1.954-.8 2.139v1.705h-1.61a.226.226 0 0 0-.226.225v2.297c0 .124.101.225.226.225Z\"><\/path>\n<\/svg>\n<\/a><\/li>\n                                          <li><a href=\"https:\/\/www.tiktok.com\/@moi_valencia?fbclid=IwY2xjawGoL5lleHRuA2FlbQIxMAABHazKeRmlxJAdZVOPussTOjLXffMwhHrFp7nLTJobM-GBJA-k7I-SWLmkrQ_aem_mMuJKfm2w0nN7ykLIuZJ7A\" target=\"_blank\" aria-label=\"MOI Twitter\" rel=\"nofollow noopener\"><svg class=\"icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"none\" viewBox=\"0 0 13 16\">\n  <path fill=\"#fff\" d=\"M11.2239 3.86306c-.0983-.05081-.1939-.10652-.2866-.16689-.2693-.17808-.5163-.38788-.7355-.6249-.54923-.62812-.75429-1.26531-.82933-1.71101h.00259C9.31231.989592 9.33819.750244 9.34272.750244H6.8425V10.4167c0 .1293 0 .2581-.00518.3849 0 .0155-.00194.0297-.00258.0472 0 .0065 0 .0142-.00194.0213v.0059c-.02626.3467-.13733.6817-.32346.9754-.18612.2937-.44158.5372-.74391.7091-.3154.1794-.67214.2735-1.03501.2729-1.1644 0-2.10886-.9496-2.10886-2.1224 0-1.17345.94446-2.12308 2.10886-2.12308.22058 0 .43988.03493.64947.1035l.00323-2.54614c-.63652-.08212-1.28316-.0314-1.8991.14897-.61594.18038-1.18779.48648-1.67947.89898-.43092.37425-.79322.82084-1.0706 1.31965-.105442.18178-.503924.91341-.551794 2.09982-.030404.6727.172072 1.3714.268458 1.6592v.0065c.06016.1695.295627.7491.678586 1.2375.30882.392.6737.7364 1.08289 1.0221v-.0065l.00582.0065c1.20968.8215 2.55197.7678 2.55197.7678.23223-.0097 1.01043 0 1.89408-.4185.98003-.4645 1.53765-1.156 1.53765-1.156.35651-.4133.64001-.8842.83836-1.3927.22641-.5952.30145-1.308.30145-1.5927V5.61677c.03041.01811.43471.28528.43471.28528s.58217.37325 1.48977.61584c.6508.17271 1.5286.20959 1.5286.20959V4.24537c-.3073.03364-.9315-.06339-1.5713-.38166l.0007-.00065Z\"\/>\n<\/svg><\/a><\/li>\n              <\/ul>\n            <div class=\"group\">\n                <ul>\n                    <li>\n            <a href=\"https:\/\/www.tripadvisor.com\/Attraction_Review-g187529-d28660000-Reviews-Museum_Of_Illusions_Valencia-Valencia_Province_of_Valencia_Valencian_Community.html\" target=\"_blank\" aria-label=\"badge\" rel=\"noopener\"> \n                          \n<picture class=\"\">\n    <source sizes=\"50vw\" media=\"(min-width: 479px)\" srcset=\"https:\/\/moivalencia.es\/wp-content\/uploads\/2026\/06\/TripAdvisor-1-1.png\" type=\"\">\n\n      <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moivalencia.es\/wp-content\/uploads\/2026\/06\/TripAdvisor-1-1.png\" data-src=\"https:\/\/moivalencia.es\/wp-content\/uploads\/2026\/06\/TripAdvisor-1-1.png\" alt=\"tripadvisor 1 1\" width=\"525\" height=\"788\">\n  <\/picture>                        <\/a>\n          \n          <\/li>\n                    <li>\n            <a href=\"#\"  aria-label=\"badge\"> \n                          \n<picture class=\"\">\n    <source sizes=\"50vw\" media=\"(min-width: 479px)\" srcset=\"https:\/\/moivalencia.es\/wp-content\/uploads\/2026\/04\/image-1.png\" type=\"\">\n\n      <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/moivalencia.es\/wp-content\/uploads\/2026\/04\/image-1.png\" data-src=\"https:\/\/moivalencia.es\/wp-content\/uploads\/2026\/04\/image-1.png\" alt=\"image (1)\" width=\"397\" height=\"114\">\n  <\/picture>                        <\/a>\n          \n          <\/li>\n                  <\/ul>\n                <p><\/p>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n\n<div class=\"footer-copyright\">\n  <div class=\"c\">\n    <div class=\"footer-copyright__left\">\n      <p>Copyright \u00a9 2022-2026 Museum of Illusions | All Rights Reserved<\/p>\n    <\/div>\n\n    <ul class=\"footer-copyright__right\">\n      <li class=\"cookies\">\n                  <a href=\"#\" data-href=\"#moove_gdpr_cookie_modal\" rel=\"nofollow\">Ajustos de Cookies<\/a>\n              <\/li>\n      <li  class=\"privacy-policy\">\n              <\/li>\n      <li><a href=\"https:\/\/builtt.io\/\" target=\"_blank\" rel=\"nofollow noopener\">Realitzat per <svg class=\"icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"13\" height=\"17\" fill=\"none\"><path fill=\"#F4F3EF\" \nd=\"M1.594 2.484v.125h.176v-.125h-.176Zm8.21 6.424v-.039c1.145-.388 2.154-1.184 2.154-2.892 0-2.212-1.67-3.493-4.522-3.493H3.728v1.844h3.805c1.455 \n0 2.192.738 2.192 1.96 0 1.243-.6 1.96-2.348 1.96H3.73v-3.92H1.594v10.19h2.134v-4.58H7.92c1.456 0 2.349.834 2.349 2.29 0 1.3-.583 2.29-2.64 2.29H3.728v1.843h4.056c2.872 \n0 4.716-1.397 4.716-4.056 0-2.077-1.241-3.144-2.697-3.397Z\"\/><path fill=\"#AF8\" d=\"M2.63.912H.5v2.13h2.13V.913Z\"\/><\/svg><\/a><\/li>\n    <\/ul>\n\n    <a class=\"degordian\" href=\"https:\/\/builtt.io\/\" target=\"_blank\" rel=\"nofollow noopener\">Realitzat per <svg class=\"icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"13\" height=\"17\" fill=\"none\"><path fill=\"#F4F3EF\" \nd=\"M1.594 2.484v.125h.176v-.125h-.176Zm8.21 6.424v-.039c1.145-.388 2.154-1.184 2.154-2.892 0-2.212-1.67-3.493-4.522-3.493H3.728v1.844h3.805c1.455 \n0 2.192.738 2.192 1.96 0 1.243-.6 1.96-2.348 1.96H3.73v-3.92H1.594v10.19h2.134v-4.58H7.92c1.456 0 2.349.834 2.349 2.29 0 1.3-.583 2.29-2.64 2.29H3.728v1.843h4.056c2.872 \n0 4.716-1.397 4.716-4.056 0-2.077-1.241-3.144-2.697-3.397Z\"\/><path fill=\"#AF8\" d=\"M2.63.912H.5v2.13h2.13V.913Z\"\/><\/svg><\/a>\n<\/div><\/footer>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":true,"footnotes":""},"class_list":["post-2730","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/moivalencia.es\/ca\/wp-json\/wp\/v2\/pages\/2730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moivalencia.es\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/moivalencia.es\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/moivalencia.es\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/moivalencia.es\/ca\/wp-json\/wp\/v2\/comments?post=2730"}],"version-history":[{"count":0,"href":"https:\/\/moivalencia.es\/ca\/wp-json\/wp\/v2\/pages\/2730\/revisions"}],"wp:attachment":[{"href":"https:\/\/moivalencia.es\/ca\/wp-json\/wp\/v2\/media?parent=2730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}